{"id":338,"date":"2021-02-07T05:19:54","date_gmt":"2021-02-07T10:19:54","guid":{"rendered":"https:\/\/hcbsas.com.co\/?page_id=338"},"modified":"2021-05-24T12:35:23","modified_gmt":"2021-05-24T17:35:23","slug":"obras-civiles","status":"publish","type":"page","link":"https:\/\/hcbsas.com.co\/index.php\/obras-civiles\/","title":{"rendered":"Obras Civiles"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.7.7&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_row _builder_version=\u00bb4.7.7&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.7.7&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_slider _builder_version=\u00bb4.7.7&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttps:\/\/hcbsas.com.co\/wp-content\/uploads\/2021\/02\/obrasciviles.png\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;][et_pb_slide heading=\u00bbObras Civiles\u00bb button_text=\u00bbServicios\u00bb button_link=\u00bbhttps:\/\/hcbsas.com.co\/index.php\/servicios\/\u00bb _builder_version=\u00bb4.7.7&#8243; _module_preset=\u00bbdefault\u00bb sticky_transition=\u00bbon\u00bb]<\/p>\n<p><span>Nuestra amplia experiencia nos permite desarrollar proyectos arquitect\u00f3nicos y civiles en el \u00e1rea de movimientos de tierra, v\u00edas, construcci\u00f3n de edificaciones para uso residencial y comercial sencillas y complejas, Mantenimiento de todo tipo de Infraestructura Civil. Instalaciones Hidrosanitarias, instalaciones el\u00e9ctricas, obras de urbanismo, estaciones de servicios restauraci\u00f3n de edificaciones con arquitectura colonial.<\/span><\/p>\n<p>[\/et_pb_slide][et_pb_slide _builder_version=\u00bb4.7.7&#8243; _module_preset=\u00bbdefault\u00bb title_text=\u00bbWhatsApp Image 2021-05-24 at 11.49.26 AM\u00bb background_image=\u00bbhttps:\/\/hcbsas.com.co\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-24-at-11.49.26-AM.jpeg\u00bb background_enable_image=\u00bbon\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243; parallax=\u00bbon\u00bb background_last_edited=\u00bboff|desktop\u00bb][\/et_pb_slide][et_pb_slide _builder_version=\u00bb4.7.7&#8243; _module_preset=\u00bbdefault\u00bb title_text=\u00bbWhatsApp Image 2021-05-24 at 11.49.26 AM (1)\u00bb background_image=\u00bbhttps:\/\/hcbsas.com.co\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-24-at-11.49.26-AM-1.jpeg\u00bb background_enable_image=\u00bbon\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;][\/et_pb_slide][et_pb_slide _builder_version=\u00bb4.7.7&#8243; _module_preset=\u00bbdefault\u00bb title_text=\u00bbWhatsApp Image 2021-05-24 at 11.49.25 AM\u00bb background_image=\u00bbhttps:\/\/hcbsas.com.co\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-24-at-11.49.25-AM.jpeg\u00bb background_enable_image=\u00bbon\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;][\/et_pb_slide][et_pb_slide _builder_version=\u00bb4.7.7&#8243; _module_preset=\u00bbdefault\u00bb title_text=\u00bbWhatsApp Image 2021-05-24 at 11.49.25 AM (2)\u00bb background_image=\u00bbhttps:\/\/hcbsas.com.co\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-24-at-11.49.25-AM-2.jpeg\u00bb background_enable_image=\u00bbon\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;][\/et_pb_slide][et_pb_slide _builder_version=\u00bb4.7.7&#8243; _module_preset=\u00bbdefault\u00bb title_text=\u00bbWhatsApp Image 2021-05-24 at 11.49.25 AM (1)\u00bb background_image=\u00bbhttps:\/\/hcbsas.com.co\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-24-at-11.49.25-AM-1.jpeg\u00bb background_enable_image=\u00bbon\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;][\/et_pb_slide][\/et_pb_slider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.7.7&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.7.7&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_text _builder_version=\u00bb4.7.7&#8243; _module_preset=\u00bbdefault\u00bb]<\/p>\n<div class=\"et_pb_column et_pb_column_1_3 et_pb_column_5  et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_module et_pb_text et_pb_text_5  et_pb_text_align_left et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<ul>\n<li>Obras Civiles en General<\/li>\n<li>Cimentaciones<\/li>\n<li>Mamposter\u00edas<\/li>\n<li>Plazas Macizas y Aligeradas<\/li>\n<li>Acabados (Obra Blanca)<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"et_pb_column et_pb_column_1_3 et_pb_column_6  et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_module et_pb_text et_pb_text_6  et_pb_text_align_left et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<ul>\n<li>Movimientos de Tierra.<\/li>\n<li>Pavimentos, Concreto Rigido, Flexible y Articulado.<\/li>\n<li>Construcci\u00f3n de Estructuras\u00a0 en Concreto y Met\u00e1licas<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"et_pb_column et_pb_column_1_3 et_pb_column_7  et_pb_css_mix_blend_mode_passthrough et-last-child\">\n<div class=\"et_pb_module et_pb_text et_pb_text_7  et_pb_text_align_left et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<ul>\n<li>Instalaci\u00f3n de Tuberias Hidra\u00falicas y Alcantarillados<\/li>\n<li>Box Culver<\/li>\n<li>Instalaci\u00f3n y Reparaci\u00f3n\u00a0 de Cubiertas (Coloniales,\u00a0 Convencionales)<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.7.7&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_row _builder_version=\u00bb4.7.7&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.7.7&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_slider _builder_version=\u00bb4.7.7&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttps:\/\/hcbsas.com.co\/wp-content\/uploads\/2021\/02\/obrasciviles.png\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;][et_pb_slide heading=\u00bbObras Civiles\u00bb button_text=\u00bbServicios\u00bb button_link=\u00bbhttps:\/\/hcbsas.com.co\/index.php\/servicios\/\u00bb _builder_version=\u00bb4.7.7&#8243; _module_preset=\u00bbdefault\u00bb sticky_transition=\u00bbon\u00bb] Nuestra amplia experiencia nos permite desarrollar proyectos arquitect\u00f3nicos y civiles en el \u00e1rea de movimientos de tierra, v\u00edas, construcci\u00f3n de edificaciones para uso residencial y comercial sencillas y complejas, Mantenimiento de todo tipo de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-338","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/hcbsas.com.co\/index.php\/wp-json\/wp\/v2\/pages\/338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hcbsas.com.co\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hcbsas.com.co\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hcbsas.com.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hcbsas.com.co\/index.php\/wp-json\/wp\/v2\/comments?post=338"}],"version-history":[{"count":6,"href":"https:\/\/hcbsas.com.co\/index.php\/wp-json\/wp\/v2\/pages\/338\/revisions"}],"predecessor-version":[{"id":394,"href":"https:\/\/hcbsas.com.co\/index.php\/wp-json\/wp\/v2\/pages\/338\/revisions\/394"}],"wp:attachment":[{"href":"https:\/\/hcbsas.com.co\/index.php\/wp-json\/wp\/v2\/media?parent=338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}